{"id":166707,"date":"2024-12-20T11:37:10","date_gmt":"2024-12-20T10:37:10","guid":{"rendered":"https:\/\/eurecat.org\/?p=166707"},"modified":"2024-12-20T11:39:05","modified_gmt":"2024-12-20T10:39:05","slug":"eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos","status":"publish","type":"post","link":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/","title":{"rendered":"Eurecat lidera un proyecto de m\u00e1s de 4 millones de euros para crear nuevos aceros 100% reciclados para la fabricaci\u00f3n de coches y electrodom\u00e9sticos"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1424.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>El centro tecnol\u00f3gico <a href=\"https:\/\/eurecat.org\/es\">Eurecat<\/a> coordina el proyecto europeo CiSMA que, con un presupuesto de cerca de 4,5 millones de euros, desarrollar\u00e1 aceros 100 por ciento reciclados a partir de chatarra y producidos en horno de arco el\u00e9ctrico, a fin de contribuir a reducir la huella de CO<sub>2<\/sub>, impulsar la econom\u00eda circular y reducir la dependencia de la Uni\u00f3n Europea en materias primas en sectores como la automoci\u00f3n y los electrodom\u00e9sticos.<\/p>\n<p>La industria europea del acero tiene como objetivo reducir las emisiones de CO<sub>2<\/sub> en un 50 por ciento en 2030 y alcanzar la neutralidad de carbono para 2050. En esta l\u00ednea, la producci\u00f3n de acero con horno de arco el\u00e9ctrico, que sustituye el proceso tradicional de alto horno, \u201cpermitir\u00e1 producir aceros de alto rendimiento para productos de consumo masivo. Esto contribuir\u00e1 a reducir en m\u00e1s del 75 por ciento las emisiones y a utilizar hasta un 100 por ciento de chatarra\u201d, afirma el coordinador t\u00e9cnico del proyecto CiSMA, Jaume Pujante, jefe de L\u00ednea de la Unidad de Materiales Met\u00e1licos y Cer\u00e1micos de Eurecat.<\/p>\n<p>Para hacerlo posible, el proyecto se centrar\u00e1 \u201cen abordar el reto de producir acero de alto rendimiento con horno de arco el\u00e9ctrico, una t\u00e9cnica que todav\u00eda no es una realidad debido al efecto de elementos residuales no deseados en la chatarra que afectan a la calidad del acero\u201d, explica la coordinadora del proyecto CiSMA, Bego\u00f1a Casas, gestora de Propuestas y Coordinaci\u00f3n Internacional en Eurecat.<\/p>\n<p>CiSMA maximizar\u00e1 el uso de chatarra de baja calidad, separando las inclusiones no deseadas con un enfoque en cobre. Para validar los desarrollos del proyecto, se llevar\u00e1n a cabo dos pruebas piloto para verificar que el material y el proceso sean aceptables por el mercado, as\u00ed como mostrar las tecnolog\u00edas desarrolladas y cuantificar las mejoras ambientales respecto al producto actual.<\/p>\n<p>En concreto, uno de los pilotos se ensayar\u00e1 con componentes de un veh\u00edculo de la marca de automoci\u00f3n Volvo Cars, y el otro, con componentes para electrodom\u00e9sticos en una lavadora industrial de Electrolux Professional.<\/p>\n<p>Adem\u00e1s, el proyecto CiSMA \u201cdesarrollar\u00e1 un conjunto de tecnolog\u00edas habilitadoras con el objetivo de introducir estos productos de acero producidos a partir de chatarra con horno de arco el\u00e9ctrico en el mercado masivo de bienes de consumo de chapa met\u00e1lica\u201d, detalla la directora de la Unidad de Materiales Met\u00e1licos y Cer\u00e1micos de Eurecat, Montse Vilaseca.<\/p>\n<p>Entre estas tecnolog\u00edas, las empresas podr\u00e1n acceder a pruebas r\u00e1pidas de caracterizaci\u00f3n de materiales met\u00e1licos para el control de calidad, nuevas metodolog\u00edas para maximizar el uso de chatarra en procesos de fabricaci\u00f3n de nuevos aceros, una herramienta de modelado de elementos finitos basada en el aprendizaje autom\u00e1tico y gemelos digitales.<\/p>\n<p>El proyecto est\u00e1 financiado por el programa Horizon Europe de la Uni\u00f3n Europea y cuenta con un consorcio formado por doce socios de cinco pa\u00edses europeos: Espa\u00f1a, Pa\u00edses Bajos, Austria, Suecia y B\u00e9lgica. El centro tecnol\u00f3gico Eurecat es el coordinador, y forman parte Tata Steel Nederland, voestalpine, Volvo Cars, Electrolux Professional, RISE Research Institutes of Sweden, Blekinge Institute of Technology, ALBA Synchroton (ALBA-CELLS), Aerobase Innovations, la plataforma europea del acero ESTEP, el CSIC y la Universidad de Lieja.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":20,"featured_media":166702,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1906,404,134],"tags":[],"class_list":["post-166707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-automocion","category-materiales-metalicos-ceramicos","category-notas-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eurecat lidera un proyecto de m\u00e1s de 4 millones de euros para crear nuevos aceros 100% reciclados para la fabricaci\u00f3n de coches y electrodom\u00e9sticos - Eurecat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eurecat lidera un proyecto de m\u00e1s de 4 millones de euros para crear nuevos aceros 100% reciclados para la fabricaci\u00f3n de coches y electrodom\u00e9sticos - Eurecat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurecat\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-20T10:37:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-20T10:39:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurecat.org\/wp-content\/uploads\/2024\/12\/Automocio_recurs_freepik_800px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"EurecatEQZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"EurecatEQZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/\"},\"author\":{\"name\":\"EurecatEQZ\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/99d4d39712001e7621b6867b27b40bed\"},\"headline\":\"Eurecat lidera un proyecto de m\u00e1s de 4 millones de euros para crear nuevos aceros 100% reciclados para la fabricaci\u00f3n de coches y electrodom\u00e9sticos\",\"datePublished\":\"2024-12-20T10:37:10+00:00\",\"dateModified\":\"2024-12-20T10:39:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/\"},\"wordCount\":1616,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Automocio_recurs_freepik_800px.jpg\",\"articleSection\":[\"Automoci\u00f3n\",\"Materiales Met\u00e1licos y Cer\u00e1micos\",\"Notas de prensa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/\",\"url\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/\",\"name\":\"Eurecat lidera un proyecto de m\u00e1s de 4 millones de euros para crear nuevos aceros 100% reciclados para la fabricaci\u00f3n de coches y electrodom\u00e9sticos - Eurecat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Automocio_recurs_freepik_800px.jpg\",\"datePublished\":\"2024-12-20T10:37:10+00:00\",\"dateModified\":\"2024-12-20T10:39:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/99d4d39712001e7621b6867b27b40bed\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Automocio_recurs_freepik_800px.jpg\",\"contentUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Automocio_recurs_freepik_800px.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/eurecat.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eurecat lidera un proyecto de m\u00e1s de 4 millones de euros para crear nuevos aceros 100% reciclados para la fabricaci\u00f3n de coches y electrodom\u00e9sticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eurecat.org\\\/es\\\/\",\"name\":\"Eurecat\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurecat.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/99d4d39712001e7621b6867b27b40bed\",\"name\":\"EurecatEQZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g\",\"caption\":\"EurecatEQZ\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eurecat lidera un proyecto de m\u00e1s de 4 millones de euros para crear nuevos aceros 100% reciclados para la fabricaci\u00f3n de coches y electrodom\u00e9sticos - Eurecat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/","og_locale":"es_ES","og_type":"article","og_title":"Eurecat lidera un proyecto de m\u00e1s de 4 millones de euros para crear nuevos aceros 100% reciclados para la fabricaci\u00f3n de coches y electrodom\u00e9sticos - Eurecat","og_url":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/","og_site_name":"Eurecat","article_published_time":"2024-12-20T10:37:10+00:00","article_modified_time":"2024-12-20T10:39:05+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/eurecat.org\/wp-content\/uploads\/2024\/12\/Automocio_recurs_freepik_800px.jpg","type":"image\/jpeg"}],"author":"EurecatEQZ","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"EurecatEQZ","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/#article","isPartOf":{"@id":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/"},"author":{"name":"EurecatEQZ","@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/99d4d39712001e7621b6867b27b40bed"},"headline":"Eurecat lidera un proyecto de m\u00e1s de 4 millones de euros para crear nuevos aceros 100% reciclados para la fabricaci\u00f3n de coches y electrodom\u00e9sticos","datePublished":"2024-12-20T10:37:10+00:00","dateModified":"2024-12-20T10:39:05+00:00","mainEntityOfPage":{"@id":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/"},"wordCount":1616,"commentCount":0,"image":{"@id":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/#primaryimage"},"thumbnailUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2024\/12\/Automocio_recurs_freepik_800px.jpg","articleSection":["Automoci\u00f3n","Materiales Met\u00e1licos y Cer\u00e1micos","Notas de prensa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/","url":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/","name":"Eurecat lidera un proyecto de m\u00e1s de 4 millones de euros para crear nuevos aceros 100% reciclados para la fabricaci\u00f3n de coches y electrodom\u00e9sticos - Eurecat","isPartOf":{"@id":"https:\/\/eurecat.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/#primaryimage"},"image":{"@id":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/#primaryimage"},"thumbnailUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2024\/12\/Automocio_recurs_freepik_800px.jpg","datePublished":"2024-12-20T10:37:10+00:00","dateModified":"2024-12-20T10:39:05+00:00","author":{"@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/99d4d39712001e7621b6867b27b40bed"},"breadcrumb":{"@id":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/#primaryimage","url":"https:\/\/eurecat.org\/wp-content\/uploads\/2024\/12\/Automocio_recurs_freepik_800px.jpg","contentUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2024\/12\/Automocio_recurs_freepik_800px.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/eurecat.org\/es\/eurecat-lidera-un-proyecto-de-mas-de-4-millones-de-euros-para-crear-nuevos-aceros-100-reciclados-para-la-fabricacion-de-coches-y-electrodomesticos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/eurecat.org\/es\/"},{"@type":"ListItem","position":2,"name":"Eurecat lidera un proyecto de m\u00e1s de 4 millones de euros para crear nuevos aceros 100% reciclados para la fabricaci\u00f3n de coches y electrodom\u00e9sticos"}]},{"@type":"WebSite","@id":"https:\/\/eurecat.org\/es\/#website","url":"https:\/\/eurecat.org\/es\/","name":"Eurecat","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurecat.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/99d4d39712001e7621b6867b27b40bed","name":"EurecatEQZ","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g","caption":"EurecatEQZ"}}]}},"_links":{"self":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/166707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/comments?post=166707"}],"version-history":[{"count":1,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/166707\/revisions"}],"predecessor-version":[{"id":166708,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/166707\/revisions\/166708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/media\/166702"}],"wp:attachment":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/media?parent=166707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/categories?post=166707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/tags?post=166707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}