{"id":175623,"date":"2025-03-31T08:50:59","date_gmt":"2025-03-31T06:50:59","guid":{"rendered":"https:\/\/eurecat.org\/?p=175623"},"modified":"2025-05-06T13:02:55","modified_gmt":"2025-05-06T11:02:55","slug":"ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida","status":"publish","type":"post","link":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/","title":{"rendered":"Ecodise\u00f1an bater\u00edas el\u00e9ctricas de autom\u00f3viles modulares para darles una segunda vida"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1424.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>El centro tecnol\u00f3gico <a href=\"https:\/\/eurecat.org\/es\">Eurecat<\/a> coordina el proyecto europeo Marbel, que ha desarrollado un nuevo concepto de bater\u00edas para veh\u00edculos el\u00e9ctricos, que apuesta por los principios de modularidad y potencial de reciclabilidad a gran escala, con el fin de reducir el impacto ambiental y fomentar la econom\u00eda circular en la industria automovil\u00edstica.<\/p>\n<p>En Catalu\u00f1a, junto con Eurecat, el proyecto ha contado con el Instituto de Investigaci\u00f3n en Energ\u00eda de Catalunya (IREC) y las empresas Applus+ IDIADA, FICOSA y OTC Engineering.<\/p>\n<p>El ecodise\u00f1o de los prototipos se ha centrado en la facilidad de ensamblaje y desensamblaje de los componentes de las bater\u00edas, con el objetivo de repercutir de forma directa en la eficiencia de su reparaci\u00f3n, reutilizaci\u00f3n en otras aplicaciones y reciclaje. Para ello, el proyecto ha incorporado hasta un 60 por ciento de aluminio reciclado posconsumo, que supone un ahorro de hasta 777 kg de CO\u2082 equivalentes por caja de bater\u00eda, y ha priorizado la modularidad para alargar la vida \u00fatil de la bater\u00eda y de sus componentes, reduciendo as\u00ed los residuos y su impacto en el medio ambiente.<\/p>\n<p>Adem\u00e1s, se han incluido innovaciones que facilitan la carga ultrarr\u00e1pida, mediante la implementaci\u00f3n de un dise\u00f1o de sistema de refrigeraci\u00f3n que garantiza una extracci\u00f3n de calor uniforme de las celdas y barras colectoras (busbars), combinado con algoritmos de optimizaci\u00f3n para el proceso de carga. Se ha incorporado tambi\u00e9n una caja de conexiones (Junction Box) que permite conmutar la arquitectura de la bater\u00eda de 400 a 800V y viceversa seg\u00fan necesidad siendo aplicable en bater\u00edas de diferente tama\u00f1o.<\/p>\n<p>\u201cEl enfoque de circularidad crea un camino hacia una tecnolog\u00eda de veh\u00edculos el\u00e9ctricos m\u00e1s sostenible, mientras que con la optimizaci\u00f3n del rendimiento de la bater\u00eda resolvemos los principales puntos cr\u00edticos para la aceptaci\u00f3n y adopci\u00f3n del coche el\u00e9ctrico, como la limitada autonom\u00eda del veh\u00edculo y el tiempo de carga, permitiendo viajar distancias m\u00e1s largas\u201d, destaca el coordinador del proyecto Marbel, Eduard Piqueras, coordinador de Programas Europeos en Eurecat.<\/p>\n<p><strong>Segunda vida de las bater\u00edas <\/strong><\/p>\n<p>Uno de los elementos clave que ha abordado el proyecto es la segunda vida de las bater\u00edas, lo que permite la reutilizaci\u00f3n y reacondicionamiento de sus componentes para aplicaciones energ\u00e9ticas m\u00e1s all\u00e1 de la automoci\u00f3n.<\/p>\n<p>\u201cAl incorporar principios de ecodise\u00f1o como la modularidad, la segunda vida y los materiales con alto contenido de reciclado y alto potencial de reciclabilidad, Marbel extiende la vida \u00fatil de las bater\u00edas y los flujos de materiales, lo que permite reducir los desechos a la vez que mantiene el valor de los materiales, avanzando tanto en sostenibilidad como en viabilidad econ\u00f3mica\u201d, detalla la investigadora de la Unidad de Residuos, Energ\u00eda e Impacto Ambiental de Eurecat Violeta Vargas.<\/p>\n<p>Poder separar m\u00e1s f\u00e1cilmente los componentes \u201cincrementa tambi\u00e9n la reparabilidad de la bater\u00eda y, en consecuencia, su vida \u00fatil, ya que es posible desmontarla f\u00e1cilmente hasta nivel de celda y volver a montarla con la misma facilidad\u201d, explica el investigador de la Unidad de Innovaci\u00f3n de Producto y Simulaci\u00f3n Multif\u00edsica de Eurecat Toni Lara.<\/p>\n<p>Marbel tambi\u00e9n ha integrado estrategias avanzadas de recuperaci\u00f3n de materiales para recuperar grafito, litio, n\u00edquel, manganeso y cobalto de alta pureza de las celdas al final de su vida \u00fatil, cumpliendo con el Reglamento Europeo sobre \u201cNormas de Sostenibilidad para Bater\u00edas y Residuos de Bater\u00edas\u201d.<\/p>\n<p><strong>Arquitectura inteligente<\/strong><\/p>\n<p>Los prototipos disponen de una arquitectura inteligente que combina conexiones de alimentaci\u00f3n mediante barras conductoras (busbars) que pueden ensamblarse y desensamblarse f\u00e1cilmente usando componentes de sujeci\u00f3n atornilladas est\u00e1ndar, y de las cuales se han optimizado sus formatos flexibles, hecho que agrega sencillez durante las operaciones de ensamblaje y les permite resistir las vibraciones a las que podr\u00eda estar sometido el paquete de bater\u00edas en el veh\u00edculo.<\/p>\n<p>Adem\u00e1s, el Sistema de Gesti\u00f3n de la Bater\u00eda (BMS) incorpora comunicaciones inal\u00e1mbricas y monitorizaci\u00f3n inteligente de energ\u00eda en tiempo real, lo que permite reducir significativamente el peso, el coste y la complejidad de dise\u00f1o. En concreto, se ha dise\u00f1ado un dispositivo electr\u00f3nico inteligente (iSCM, Smart Cell Manager) que se integra en cada celda de la bater\u00eda, permitiendo la monitorizaci\u00f3n local de cada celda y la comunicaci\u00f3n directa con el BMS a trav\u00e9s de tecnolog\u00eda inal\u00e1mbrica Bluetooth.<\/p>\n<p>De esta manera, por ejemplo, el cableado de un paquete de bater\u00edas de 16 celdas se reduce de m\u00e1s de 20 metros a apenas 80 cent\u00edmetros, lo que reduce los costes de material, el peso y la complejidad de ensamblaje.<\/p>\n<p>Los datos recopilados por el BMS, junto con los generados por iSCM, se integran en un sistema de gemelo digital basado en algoritmos de inteligencia artificial y aprendizaje autom\u00e1tico que realiza procesos de anal\u00edtica predictiva, incorporando informaci\u00f3n de diferentes fuentes en una \u00fanica aplicaci\u00f3n web. El sistema puede predecir la vida \u00fatil restante de la bater\u00eda, su estado de carga y salud, as\u00ed como el momento en que alcanzar\u00e1 el final de su vida \u00fatil, entre otros elementos. Esto permite disponer de informaci\u00f3n veraz para planificar una segunda vida \u00fatil en funci\u00f3n del estado de salud de los componentes.<\/p>\n<p>El proyecto, que ha contado con un presupuesto de 11 millones de euros, ha sido financiado del programa H2020 de la Uni\u00f3n Europea. El consorcio Marbel ha reunido 16 socios de ocho pa\u00edses europeos, entre los cuales seis universidades y centros de investigaci\u00f3n, una empresa de ingenier\u00eda de automoci\u00f3n, dos pymes, una OEM y cinco fabricantes de componentes.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":20,"featured_media":175621,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1906,400,134,2582],"tags":[],"class_list":["post-175623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-automocion","category-desarrollo-producto","category-notas-de-prensa","category-weei-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecodise\u00f1an bater\u00edas el\u00e9ctricas de autom\u00f3viles modulares para darles una segunda vida - Eurecat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecodise\u00f1an bater\u00edas el\u00e9ctricas de autom\u00f3viles modulares para darles una segunda vida - Eurecat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurecat\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-31T06:50:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T11:02:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/04\/Projecte_Marbel_800px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"574\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"EurecatEQZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"EurecatEQZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/\"},\"author\":{\"name\":\"EurecatEQZ\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/99d4d39712001e7621b6867b27b40bed\"},\"headline\":\"Ecodise\u00f1an bater\u00edas el\u00e9ctricas de autom\u00f3viles modulares para darles una segunda vida\",\"datePublished\":\"2025-03-31T06:50:59+00:00\",\"dateModified\":\"2025-05-06T11:02:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/\"},\"wordCount\":2052,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Projecte_Marbel_800px.webp\",\"articleSection\":[\"Automoci\u00f3n\",\"Desarrollo de Producto\",\"Notas de prensa\",\"WEEI\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/\",\"url\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/\",\"name\":\"Ecodise\u00f1an bater\u00edas el\u00e9ctricas de autom\u00f3viles modulares para darles una segunda vida - Eurecat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Projecte_Marbel_800px.webp\",\"datePublished\":\"2025-03-31T06:50:59+00:00\",\"dateModified\":\"2025-05-06T11:02:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/99d4d39712001e7621b6867b27b40bed\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Projecte_Marbel_800px.webp\",\"contentUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Projecte_Marbel_800px.webp\",\"width\":800,\"height\":574},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/eurecat.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecodise\u00f1an bater\u00edas el\u00e9ctricas de autom\u00f3viles modulares para darles una segunda vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eurecat.org\\\/es\\\/\",\"name\":\"Eurecat\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurecat.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/99d4d39712001e7621b6867b27b40bed\",\"name\":\"EurecatEQZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/litespeed\\\/avatar\\\/bdaf143b16804d09126bb60efee439f6.jpg?ver=1788258185\",\"url\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/litespeed\\\/avatar\\\/bdaf143b16804d09126bb60efee439f6.jpg?ver=1788258185\",\"contentUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/litespeed\\\/avatar\\\/bdaf143b16804d09126bb60efee439f6.jpg?ver=1788258185\",\"caption\":\"EurecatEQZ\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecodise\u00f1an bater\u00edas el\u00e9ctricas de autom\u00f3viles modulares para darles una segunda vida - Eurecat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/","og_locale":"es_ES","og_type":"article","og_title":"Ecodise\u00f1an bater\u00edas el\u00e9ctricas de autom\u00f3viles modulares para darles una segunda vida - Eurecat","og_url":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/","og_site_name":"Eurecat","article_published_time":"2025-03-31T06:50:59+00:00","article_modified_time":"2025-05-06T11:02:55+00:00","og_image":[{"width":800,"height":574,"url":"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/04\/Projecte_Marbel_800px.jpg","type":"image\/jpeg"}],"author":"EurecatEQZ","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"EurecatEQZ","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/#article","isPartOf":{"@id":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/"},"author":{"name":"EurecatEQZ","@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/99d4d39712001e7621b6867b27b40bed"},"headline":"Ecodise\u00f1an bater\u00edas el\u00e9ctricas de autom\u00f3viles modulares para darles una segunda vida","datePublished":"2025-03-31T06:50:59+00:00","dateModified":"2025-05-06T11:02:55+00:00","mainEntityOfPage":{"@id":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/"},"wordCount":2052,"commentCount":0,"image":{"@id":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/04\/Projecte_Marbel_800px.webp","articleSection":["Automoci\u00f3n","Desarrollo de Producto","Notas de prensa","WEEI"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/","url":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/","name":"Ecodise\u00f1an bater\u00edas el\u00e9ctricas de autom\u00f3viles modulares para darles una segunda vida - Eurecat","isPartOf":{"@id":"https:\/\/eurecat.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/#primaryimage"},"image":{"@id":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/04\/Projecte_Marbel_800px.webp","datePublished":"2025-03-31T06:50:59+00:00","dateModified":"2025-05-06T11:02:55+00:00","author":{"@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/99d4d39712001e7621b6867b27b40bed"},"breadcrumb":{"@id":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/#primaryimage","url":"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/04\/Projecte_Marbel_800px.webp","contentUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/04\/Projecte_Marbel_800px.webp","width":800,"height":574},{"@type":"BreadcrumbList","@id":"https:\/\/eurecat.org\/es\/ecodisenan-baterias-electricas-de-automoviles-modulares-para-darles-una-segunda-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/eurecat.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ecodise\u00f1an bater\u00edas el\u00e9ctricas de autom\u00f3viles modulares para darles una segunda vida"}]},{"@type":"WebSite","@id":"https:\/\/eurecat.org\/es\/#website","url":"https:\/\/eurecat.org\/es\/","name":"Eurecat","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurecat.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/99d4d39712001e7621b6867b27b40bed","name":"EurecatEQZ","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurecat.org\/wp-content\/litespeed\/avatar\/bdaf143b16804d09126bb60efee439f6.jpg?ver=1788258185","url":"https:\/\/eurecat.org\/wp-content\/litespeed\/avatar\/bdaf143b16804d09126bb60efee439f6.jpg?ver=1788258185","contentUrl":"https:\/\/eurecat.org\/wp-content\/litespeed\/avatar\/bdaf143b16804d09126bb60efee439f6.jpg?ver=1788258185","caption":"EurecatEQZ"}}]}},"_links":{"self":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/175623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/comments?post=175623"}],"version-history":[{"count":2,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/175623\/revisions"}],"predecessor-version":[{"id":179233,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/175623\/revisions\/179233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/media\/175621"}],"wp:attachment":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/media?parent=175623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/categories?post=175623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/tags?post=175623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}