{"id":190593,"date":"2025-11-25T15:33:25","date_gmt":"2025-11-25T14:33:25","guid":{"rendered":"https:\/\/eurecat.org\/?p=190593"},"modified":"2025-11-25T15:35:01","modified_gmt":"2025-11-25T14:35:01","slug":"eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos","status":"publish","type":"post","link":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/","title":{"rendered":"Eurecat, pionero en el desarrollo de robots agr\u00edcolas aut\u00f3nomos e inteligentes para el cuidado y la cosecha de los cultivos"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1424.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>El centro tecnol\u00f3gico <a href=\"http:\/\/eurecat.org\/es\/\">Eurecat<\/a> muestra, a partir de hoy, en el Agrobiotech Innovation Forum en Lleida, robots agr\u00edcolas aut\u00f3nomos que realizan la pulverizaci\u00f3n, la fumigaci\u00f3n, el cuidado y la cosecha de cultivos mediante la integraci\u00f3n de tecnolog\u00edas como la inteligencia artificial, la percepci\u00f3n inteligente, los algoritmos de decisi\u00f3n o la navegaci\u00f3n aut\u00f3noma.<\/p>\n<p>La automatizaci\u00f3n de tareas cr\u00edticas en el campo contribuye a avanzar hacia una agricultura de precisi\u00f3n avanzada y \u201caporta soluciones concretas a los desaf\u00edos que los efectos del cambio clim\u00e1tico, la escasez de mano de obra y la necesidad de optimizar recursos y mejorar la productividad, plantean al sector agr\u00edcola\u201d, se\u00f1ala la responsable de Negocio del Mercado Alimentaci\u00f3n de Eurecat, Carol Bened\u00ed.<\/p>\n<p>En esta l\u00ednea, Eurecat destaca por su \u201ccapacidad de integraci\u00f3n de m\u00faltiples tecnolog\u00edas diferenciales para resolver necesidades reales, acelerar la innovaci\u00f3n y transformar el conocimiento en soluciones probadas, escalables y con impacto directo en la competitividad de las empresas y el incremento de la resiliencia del sector agroalimentario\u201d, apunta el director de Rob\u00f3tica y Automatizaci\u00f3n de Eurecat, Daniel Serrano.<\/p>\n<p><strong>Rob\u00f3tica para optimizar la gesti\u00f3n del campo y mejorar la productividad<\/strong><\/p>\n<p>En esta l\u00ednea, Eurecat demuestra en el Agrobiotech Innovation Forum el funcionamiento del robot aut\u00f3nomo desarrollado con la empresa GeoEntec Environment Technologies para la automatizaci\u00f3n de la pulverizaci\u00f3n de los cultivos y la aplicaci\u00f3n de fitosanitarios en invernaderos y con hortalizas tutorizadas.<\/p>\n<p>La soluci\u00f3n, denominada ROVAG, es una plataforma rob\u00f3tica multifunci\u00f3n modular para la agricultura en invernadero que incorpora tecnolog\u00edas avanzadas de sens\u00f3rica y de navegaci\u00f3n y percepci\u00f3n autom\u00e1tica, que le permiten operar de manera aut\u00f3noma y desplazarse tanto en interiores como en exteriores.<\/p>\n<p>Adem\u00e1s, al estar dotada de inteligencia artificial, realiza el proceso de aplicaci\u00f3n de fitosanitarios de manera completa, desde la planificaci\u00f3n hasta la adaptaci\u00f3n de la gota del tratamiento seg\u00fan el crecimiento y estado de salud de la planta, y su aplicaci\u00f3n. A la vez, esta tecnolog\u00eda le permite realizar la predicci\u00f3n de cosecha y la detecci\u00f3n prematura de problemas fitosanitarios.<\/p>\n<p>En palabras del responsable de Rob\u00f3tica M\u00f3vil de Eurecat, Carlos Rizzo, \u201cROVAG en la colaboraci\u00f3n con GeoEntec es un ejemplo de c\u00f3mo Eurecat trabaja junto al tejido empresarial para trasladar tecnolog\u00edas como la combinaci\u00f3n de la rob\u00f3tica y la inteligencia artificial a soluciones reales, codise\u00f1adas y adaptadas a las necesidades del campo, validadas junto con los productores y listas para escalarse\u201d.<\/p>\n<p><strong>Premio al \u201cProyecto del A\u00f1o\u201d para la soluci\u00f3n ROVAG<\/strong><\/p>\n<p>Por esta plataforma rob\u00f3tica aut\u00f3noma, que ha contado en su desarrollo con Eurecat como principal desarrollador e integrador tecnol\u00f3gico, la empresa GeoEntec Environment Technologies ha ganado recientemente el premio al \u201cProyecto del A\u00f1o\u201d en la Noche de la Rob\u00f3tica que organiza el Colegio de Ingenieros Industriales de Catalu\u00f1a.<\/p>\n<p>Por otro lado, en su estand, Eurecat muestra el robot HarvBot, implementado con la empresa Enkitek, que incorpora sensores, inteligencia y visi\u00f3n artificial para localizar y recolectar frutos, evaluar su madurez y detectar posibles defectos. Probado en cultivos de pepino hidrop\u00f3nicos, sin suelo, el dispositivo cuenta con un brazo rob\u00f3tico que est\u00e1 dotado de una pinza especializada para manipular los frutos de manera aut\u00f3noma y segura.<\/p>\n<p>Adem\u00e1s, Eurecat presenta tambi\u00e9n un robot terrestre que permite la monitorizaci\u00f3n de los cultivos y el transporte aut\u00f3nomo de frutas en terrenos irregulares, equipado con percepci\u00f3n 3D para la comprensi\u00f3n del entorno y con razonamiento sem\u00e1ntico para una toma de decisiones inteligente.<\/p>\n<p>Esta soluci\u00f3n se gestiona mediante la plataforma SOMAgro, una aplicaci\u00f3n multirrobot desarrollada con Grupo Salt\u00f3, para la coordinaci\u00f3n de flotas y la asignaci\u00f3n y control de tareas por parte de los agricultores.<\/p>\n<p><strong>Un nuevo sistema agrovoltaico<\/strong><\/p>\n<p>Eurecat anticipa en su estand un sistema agrovoltaico, implementado en el proyecto europeo SYNATRA, que cuenta con m\u00f3dulos fotovoltaicos org\u00e1nicos, flexibles y semitransparentes elaborados mediante tecnolog\u00eda de electr\u00f3nica impresa, que incorporan materiales espec\u00edficamente seleccionados para asegurar la combinaci\u00f3n de la absorci\u00f3n de luz con el crecimiento de las plantas en la actividad agr\u00edcola.<\/p>\n<p>Las c\u00e9lulas solares de esta soluci\u00f3n, en el \u00e1mbito de la sostenibilidad y la mitigaci\u00f3n del cambio clim\u00e1tico, est\u00e1n compuestas por materiales org\u00e1nicos, que les confieren propiedades de flexibilidad, ligereza y una mayor reciclabilidad que las convencionales.<\/p>\n<p>En cuanto a la bioeconom\u00eda y la descarbonizaci\u00f3n, Eurecat destaca la circularidad para convertir residuos y subproductos en nuevos flujos de valor, la introducci\u00f3n de vectores energ\u00e9ticos como el hidr\u00f3geno renovable y nuevas rutas del carbono para hacerlo circular, para aportar eficiencia y sostenibilidad a la industria agr\u00edcola.<\/p>\n<p><strong>Estrategias para la salud de los suelos agr\u00edcolas<\/strong><\/p>\n<p>Adem\u00e1s, el centro tecnol\u00f3gico anticipa soluciones pioneras de remediaci\u00f3n de suelos agr\u00edcolas mediante el uso de la biotecnolog\u00eda y de ciencias \u00f3micas como la metagen\u00f3mica, la metabol\u00f3mica y la prote\u00f3mica, para la caracterizaci\u00f3n de la salud del suelo a escala microbiana y molecular, la identificaci\u00f3n de contaminaciones o desequilibrios, y la propuesta de estrategias naturales y regenerativas de recuperaci\u00f3n de la fertilidad del suelo.<\/p>\n<p>Estos desarrollos abren el camino a nuevas estrategias de fertilizaci\u00f3n inteligente y de regeneraci\u00f3n ed\u00e1fica que contribuyen a adaptar la agricultura ante los efectos del cambio clim\u00e1tico y de las normativas ambientales.<\/p>\n<p>Por otro lado, en el marco del foro de innovaci\u00f3n, varias voces expertas de Eurecat comparten las claves de la transformaci\u00f3n del sector agr\u00edcola con la innovaci\u00f3n en tecnolog\u00edas como la rob\u00f3tica, la inteligencia artificial, la descarbonizaci\u00f3n, la regeneraci\u00f3n del agua, la econom\u00eda circular o la insecticultura.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":20,"featured_media":190598,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1905,393,399,134,408],"tags":[],"class_list":["post-190593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentacion","category-ciencias-omicas","category-impresion-funcional","category-notas-de-prensa","category-robotica-automatizacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eurecat, pionero en el desarrollo de robots agr\u00edcolas aut\u00f3nomos e inteligentes para el cuidado y la cosecha de los cultivos - Eurecat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eurecat, pionero en el desarrollo de robots agr\u00edcolas aut\u00f3nomos e inteligentes para el cuidado y la cosecha de los cultivos - Eurecat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurecat\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-25T14:33:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T14:35:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/11\/Eurecat-Agrobiotech-Innovation-Forum_800px2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"EurecatEQZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"EurecatEQZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/\"},\"author\":{\"name\":\"EurecatEQZ\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/99d4d39712001e7621b6867b27b40bed\"},\"headline\":\"Eurecat, pionero en el desarrollo de robots agr\u00edcolas aut\u00f3nomos e inteligentes para el cuidado y la cosecha de los cultivos\",\"datePublished\":\"2025-11-25T14:33:25+00:00\",\"dateModified\":\"2025-11-25T14:35:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/\"},\"wordCount\":2145,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Eurecat-Agrobiotech-Innovation-Forum_800px2.jpg\",\"articleSection\":[\"Alimentaci\u00f3n\",\"Ciencias \u00d3micas\",\"Impresi\u00f3n funcional\",\"Notas de prensa\",\"Rob\u00f3tica y Automatizaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/\",\"url\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/\",\"name\":\"Eurecat, pionero en el desarrollo de robots agr\u00edcolas aut\u00f3nomos e inteligentes para el cuidado y la cosecha de los cultivos - Eurecat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Eurecat-Agrobiotech-Innovation-Forum_800px2.jpg\",\"datePublished\":\"2025-11-25T14:33:25+00:00\",\"dateModified\":\"2025-11-25T14:35:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/99d4d39712001e7621b6867b27b40bed\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Eurecat-Agrobiotech-Innovation-Forum_800px2.jpg\",\"contentUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Eurecat-Agrobiotech-Innovation-Forum_800px2.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/eurecat.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eurecat, pionero en el desarrollo de robots agr\u00edcolas aut\u00f3nomos e inteligentes para el cuidado y la cosecha de los cultivos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eurecat.org\\\/es\\\/\",\"name\":\"Eurecat\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurecat.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/99d4d39712001e7621b6867b27b40bed\",\"name\":\"EurecatEQZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g\",\"caption\":\"EurecatEQZ\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eurecat, pionero en el desarrollo de robots agr\u00edcolas aut\u00f3nomos e inteligentes para el cuidado y la cosecha de los cultivos - Eurecat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/","og_locale":"es_ES","og_type":"article","og_title":"Eurecat, pionero en el desarrollo de robots agr\u00edcolas aut\u00f3nomos e inteligentes para el cuidado y la cosecha de los cultivos - Eurecat","og_url":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/","og_site_name":"Eurecat","article_published_time":"2025-11-25T14:33:25+00:00","article_modified_time":"2025-11-25T14:35:01+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/11\/Eurecat-Agrobiotech-Innovation-Forum_800px2.jpg","type":"image\/jpeg"}],"author":"EurecatEQZ","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"EurecatEQZ","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/#article","isPartOf":{"@id":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/"},"author":{"name":"EurecatEQZ","@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/99d4d39712001e7621b6867b27b40bed"},"headline":"Eurecat, pionero en el desarrollo de robots agr\u00edcolas aut\u00f3nomos e inteligentes para el cuidado y la cosecha de los cultivos","datePublished":"2025-11-25T14:33:25+00:00","dateModified":"2025-11-25T14:35:01+00:00","mainEntityOfPage":{"@id":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/"},"wordCount":2145,"commentCount":0,"image":{"@id":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/#primaryimage"},"thumbnailUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/11\/Eurecat-Agrobiotech-Innovation-Forum_800px2.jpg","articleSection":["Alimentaci\u00f3n","Ciencias \u00d3micas","Impresi\u00f3n funcional","Notas de prensa","Rob\u00f3tica y Automatizaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/","url":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/","name":"Eurecat, pionero en el desarrollo de robots agr\u00edcolas aut\u00f3nomos e inteligentes para el cuidado y la cosecha de los cultivos - Eurecat","isPartOf":{"@id":"https:\/\/eurecat.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/#primaryimage"},"image":{"@id":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/#primaryimage"},"thumbnailUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/11\/Eurecat-Agrobiotech-Innovation-Forum_800px2.jpg","datePublished":"2025-11-25T14:33:25+00:00","dateModified":"2025-11-25T14:35:01+00:00","author":{"@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/99d4d39712001e7621b6867b27b40bed"},"breadcrumb":{"@id":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/#primaryimage","url":"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/11\/Eurecat-Agrobiotech-Innovation-Forum_800px2.jpg","contentUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2025\/11\/Eurecat-Agrobiotech-Innovation-Forum_800px2.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/eurecat.org\/es\/eurecat-pionero-en-el-desarrollo-de-robots-agricolas-autonomos-e-inteligentes-para-el-cuidado-y-la-cosecha-de-los-cultivos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/eurecat.org\/es\/"},{"@type":"ListItem","position":2,"name":"Eurecat, pionero en el desarrollo de robots agr\u00edcolas aut\u00f3nomos e inteligentes para el cuidado y la cosecha de los cultivos"}]},{"@type":"WebSite","@id":"https:\/\/eurecat.org\/es\/#website","url":"https:\/\/eurecat.org\/es\/","name":"Eurecat","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurecat.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/99d4d39712001e7621b6867b27b40bed","name":"EurecatEQZ","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6deb26ca61bcc34263c59cc62bb8b08ff90b67af7f99943babf5d86396845993?s=96&d=mm&r=g","caption":"EurecatEQZ"}}]}},"_links":{"self":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/190593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/comments?post=190593"}],"version-history":[{"count":1,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/190593\/revisions"}],"predecessor-version":[{"id":190594,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/190593\/revisions\/190594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/media\/190598"}],"wp:attachment":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/media?parent=190593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/categories?post=190593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/tags?post=190593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}