{"id":25519,"date":"2017-05-17T13:52:17","date_gmt":"2017-05-17T13:52:17","guid":{"rendered":"https:\/\/eurecat.org\/?p=25519\/"},"modified":"2017-05-17T15:32:44","modified_gmt":"2017-05-17T15:32:44","slug":"ransomware-moviles-objetos-iot","status":"publish","type":"post","link":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/","title":{"rendered":"\u00abEl ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1n objetos IoT\u00bb"},"content":{"rendered":"<p><strong>El ciberataque global causado por el gusano inform\u00e1tico #Wannacry ha puesto de manifiesto las vulnerabilidades en materia de ciberseguridad de infraestructuras cr\u00edticas y empresas. Este tipo de ataques inform\u00e1ticos basados \u200b\u200ben la extorsi\u00f3n econ\u00f3mica son una de las principales amenazas que tendr\u00e1n que hacer frente empresas y usuarios en los pr\u00f3ximos a\u00f1os, especialmente con el desarrollo de la Internet de las Cosas.<\/strong><\/p>\n<p><strong>En esta entrevista Samuel Exp\u00f3sito, jefe de l\u00ednea de Ciberseguridad de la unidad de IT Security de Eurecat, analiza los principales riesgos y ofrece recomendaciones para proteger la ciberseguridad de empresas y usuarios.<\/strong><\/p>\n<p><strong>\u00bfPor qu\u00e9 se utiliza el ransomware contra las empresas?<\/strong><\/p>\n<p>El ransomware es un tipo de ataque inform\u00e1tico basado en la extorsi\u00f3n. <strong>El objetivo no es conseguir informaci\u00f3n confidencial de las empresas, sino \u00absecuestrarla\u00bb y pedir dinero a cambio<\/strong>. Para ello, se ataca al eslab\u00f3n m\u00e1s d\u00e9bil de la seguridad de una empresa: el trabajador.<\/p>\n<p><strong>\u00bfCu\u00e1l es la t\u00e9cnica m\u00e1s utilizada para provocar este tipo de ataques?<\/strong><\/p>\n<p>Se env\u00edan correos electr\u00f3nicos con documentos adjuntos maliciosos que una vez abiertos inician un proceso de cifrado del disco duro. Los ransomwares m\u00e1s sofisticados no s\u00f3lo cifran el disco duro de la m\u00e1quina de la v\u00edctima. Tambi\u00e9n lo hacen con las unidades compartidas que est\u00e9n conectadas en ese momento.<\/p>\n<p>Al final del proceso, al usuario s\u00f3lo se le muestra una ventana con una direcci\u00f3n de bitcoins donde se solicita un pago. <strong>El cifrado utilizado es muy robusto<\/strong>. Por lo tanto, si se quieren recuperar los datos s\u00f3lo hay dos opciones: restaurar una copia de seguridad o hacer el pago.<\/p>\n<div id=\"attachment_25525\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-25525\" class=\"wp-image-25525 size-full\" src=\"https:\/\/eurecat.org\/wp-content\/uploads\/2017\/05\/Ransomware-bitcoin-demand-935625.jpg\" alt=\"\" width=\"590\" height=\"441\" \/><p id=\"caption-attachment-25525\" class=\"wp-caption-text\">Una pantalla de ransomware de demanada de bitcoins<\/p><\/div>\n<p><strong>\u00bfQu\u00e9 particularidad tiene el ransomware utilizado estos d\u00edas para atacar infraestructuras cr\u00edticas y empresas?<\/strong><\/p>\n<p>Este ransomware es una variante m\u00e1s avanzada del ataque cl\u00e1sico. <strong>Tiene la peculiaridad de que es un gusano, no un virus<\/strong>. La diferencia fundamental entre virus y gusano en el \u00e1mbito de la seguridad inform\u00e1tica es que el gusano est\u00e1 programado para propagarse autom\u00e1ticamente sin la ayuda de un usuario.<\/p>\n<p>En este caso, se ha utilizado una vulnerabilidad de Windows que fue publicada en el mes de marzo. Todos los ordenadores de la misma red local de la v\u00edctima inicial que no hubieran aplicado las mejoras en seguridad publicadas por Microsoft Windows eran vulnerables y susceptibles de ser infectadas.<\/p>\n<p><strong>\u00bfPor qu\u00e9 es uno de los principales m\u00e9todos para atacar empresas?<\/strong><\/p>\n<p>La p\u00e9rdida de datos puede suponer un golpe muy fuerte en el balance de una empresa, y esto es una realidad que conocen los atacantes. Por lo tanto, la t\u00e9cnica del ransomware se convierte en un ataque altamente efectivo en caso de infectar una m\u00e1quina importante y no tener copia de seguridad.<\/p>\n<p><strong>Es muy rentable<\/strong> en caso de \u00e9xito <strong>y seguro<\/strong>, ya que el atacante se cubre muy bien las espaldas con el anonimato que proporciona la <a href=\"https:\/\/www.xataka.com\/analisis\/una-semana-en-la-deep-web-esto-es-lo-que-me-he-encontrado\">Deep web<\/a> y las <a href=\"https:\/\/hipertextual.com\/2017\/05\/bitcoin-punto-mira-ciberataque-ransomware\">transacciones de bitcoins<\/a>.<\/p>\n<p><strong>\u00bfPor qu\u00e9 se pide un pago en bitcoins?<\/strong><\/p>\n<p>Se trata de transacciones dif\u00edciles de rastrear y por eso es habitual en casos de ransomware.<strong> El sistema de bitcoins permite que cualquier transacci\u00f3n sea p\u00fablica y visible para todo el mundo, pero no vincula con facilidad emisores y receptores en la vida real<\/strong>. Adem\u00e1s, una vez se realiza el pago, el atacante puede quedarse los bitcoins, cambiar sus bitcoins por otras monedas, o comprar activos con esta moneda.<\/p>\n<p><strong>\u00bfQu\u00e9 medida debemos tomar para protegernos de ataques similares?<\/strong><\/p>\n<p>Ahora est\u00e1 sucediendo en ordenadores. Pero el ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1n objetos IoT.<\/p>\n<p>Aunque es complicado protegernos de este tipo de ataques, hay que prevenirlos siguiendo las normas b\u00e1sicas de seguridad. Tambi\u00e9n es necesario que el fabricante garantice un mantenimiento continuo del dispositivo.<strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p><strong>\u00bfCu\u00e1les son las principales afectaciones de seguridad en objetos conectados?<\/strong><\/p>\n<p>Normalmente la privacidad de la persona es la que queda vulnerada. Sin embargo, en casos de cerraduras electr\u00f3nicas o persianas autom\u00e1ticas, se pueden dar robos y\/o da\u00f1os materiales.<\/p>\n<p>Ya se han dado casos de televisiones con c\u00e1mara para videoconferencia donde la privacidad de los usuarios ha sido completamente violada. O tambi\u00e9n c\u00e1maras de vigilancia a las que todo el mundo puede acceder e incluso controlar.<\/p>\n<div id=\"attachment_25529\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-25529\" class=\"wp-image-25529 size-medium\" src=\"https:\/\/eurecat.org\/wp-content\/uploads\/2017\/05\/Captura-de-pantalla-2017-05-17-a-las-16.10.49-300x269.png\" alt=\"\" width=\"300\" height=\"269\" \/><p id=\"caption-attachment-25529\" class=\"wp-caption-text\">Ejemplo de una c\u00e1mara de videovigilancia hackeada<\/p><\/div>\n<p><strong>Los usuarios deben seguir las recomendaciones de seguridad b\u00e1sicas ofrecidas por el fabricante<\/strong> como cambiar la contrase\u00f1a.<\/p>\n<p><strong>\u00bfCrees que la industria est\u00e1 preparada para hacer el cambio?<\/strong><\/p>\n<p>El usuario que compra un producto conf\u00eda en que este dispositivo sea seguro y que haya pasado una auditor\u00eda de calidad y de seguridad. Y eso no siempre es cierto. En Europa todos los productos pasan un test de calidad y durabilidad m\u00ednima. Hay pocas empresas que validen que cuando un producto sale al mercado lo haga con un nivel m\u00ednimo de seguridad.<\/p>\n<p>Pero <strong>esto cambiar\u00e1 durante los pr\u00f3ximos a\u00f1os<\/strong>, ya que cada vez hay m\u00e1s dispositivos conectados y se necesitar\u00e1 una relaci\u00f3n de confianza m\u00ednima. <strong>Es necesario hacer este cambio<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ciberataque global causado por el gusano inform\u00e1tico #Wannacry ha puesto de manifiesto las vulnerabilidades en materia de ciberseguridad de infraestructuras cr\u00edticas y empresas. Este tipo de ataques inform\u00e1ticos basados \u200b\u200ben la extorsi\u00f3n econ\u00f3mica son una de las principales amenazas que tendr\u00e1n que hacer frente empresas y usuarios en los pr\u00f3ximos a\u00f1os, especialmente con el  [&#8230;]<\/p>\n","protected":false},"author":6,"featured_media":25539,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133,401],"tags":[818,816,815],"class_list":["post-25519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-it-security-es","tag-ciberseguridad","tag-que-es-ransomware","tag-ransomware"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;El ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1 la IoT&quot;<\/title>\n<meta name=\"description\" content=\"An\u00e1lisis de por qu\u00e9 los ransomware, los ataques inform\u00e1ticos basados en la extorsi\u00f3n econ\u00f3mica, son una de las principales amenazas para empresas y usuarios\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;El ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1 la IoT&quot;\" \/>\n<meta property=\"og:description\" content=\"An\u00e1lisis de por qu\u00e9 los ransomware, los ataques inform\u00e1ticos basados en la extorsi\u00f3n econ\u00f3mica, son una de las principales amenazas para empresas y usuarios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurecat\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-17T13:52:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-17T15:32:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurecat.org\/wp-content\/uploads\/2017\/05\/ransomware-ciberseguretat-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"659\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"EurecatEM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"EurecatEM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/\"},\"author\":{\"name\":\"EurecatEM\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/540d47fd9da63c4587cbae01b88e4db3\"},\"headline\":\"\u00abEl ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1n objetos IoT\u00bb\",\"datePublished\":\"2017-05-17T13:52:17+00:00\",\"dateModified\":\"2017-05-17T15:32:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/\"},\"wordCount\":913,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ransomware-ciberseguretat-3.webp\",\"keywords\":[\"ciberseguridad\",\"qu\u00e8 \u00e9s ransomware\",\"ransomware\"],\"articleSection\":[\"Blog\",\"IT-Security\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/\",\"url\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/\",\"name\":\"\\\"El ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1 la IoT\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ransomware-ciberseguretat-3.webp\",\"datePublished\":\"2017-05-17T13:52:17+00:00\",\"dateModified\":\"2017-05-17T15:32:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/540d47fd9da63c4587cbae01b88e4db3\"},\"description\":\"An\u00e1lisis de por qu\u00e9 los ransomware, los ataques inform\u00e1ticos basados en la extorsi\u00f3n econ\u00f3mica, son una de las principales amenazas para empresas y usuarios\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ransomware-ciberseguretat-3.webp\",\"contentUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/ransomware-ciberseguretat-3.webp\",\"width\":1200,\"height\":659},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/ransomware-moviles-objetos-iot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/eurecat.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abEl ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1n objetos IoT\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eurecat.org\\\/es\\\/\",\"name\":\"Eurecat\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurecat.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/540d47fd9da63c4587cbae01b88e4db3\",\"name\":\"EurecatEM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/litespeed\\\/avatar\\\/ccde36d44b1cd8c84b09d53c1e5a94a8.jpg?ver=1784026185\",\"url\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/litespeed\\\/avatar\\\/ccde36d44b1cd8c84b09d53c1e5a94a8.jpg?ver=1784026185\",\"contentUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/litespeed\\\/avatar\\\/ccde36d44b1cd8c84b09d53c1e5a94a8.jpg?ver=1784026185\",\"caption\":\"EurecatEM\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"El ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1 la IoT\"","description":"An\u00e1lisis de por qu\u00e9 los ransomware, los ataques inform\u00e1ticos basados en la extorsi\u00f3n econ\u00f3mica, son una de las principales amenazas para empresas y usuarios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/","og_locale":"es_ES","og_type":"article","og_title":"\"El ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1 la IoT\"","og_description":"An\u00e1lisis de por qu\u00e9 los ransomware, los ataques inform\u00e1ticos basados en la extorsi\u00f3n econ\u00f3mica, son una de las principales amenazas para empresas y usuarios","og_url":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/","og_site_name":"Eurecat","article_published_time":"2017-05-17T13:52:17+00:00","article_modified_time":"2017-05-17T15:32:44+00:00","og_image":[{"width":1200,"height":659,"url":"https:\/\/eurecat.org\/wp-content\/uploads\/2017\/05\/ransomware-ciberseguretat-3.jpg","type":"image\/jpeg"}],"author":"EurecatEM","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"EurecatEM","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/#article","isPartOf":{"@id":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/"},"author":{"name":"EurecatEM","@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/540d47fd9da63c4587cbae01b88e4db3"},"headline":"\u00abEl ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1n objetos IoT\u00bb","datePublished":"2017-05-17T13:52:17+00:00","dateModified":"2017-05-17T15:32:44+00:00","mainEntityOfPage":{"@id":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/"},"wordCount":913,"commentCount":0,"image":{"@id":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/#primaryimage"},"thumbnailUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2017\/05\/ransomware-ciberseguretat-3.webp","keywords":["ciberseguridad","qu\u00e8 \u00e9s ransomware","ransomware"],"articleSection":["Blog","IT-Security"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/","url":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/","name":"\"El ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1 la IoT\"","isPartOf":{"@id":"https:\/\/eurecat.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/#primaryimage"},"image":{"@id":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/#primaryimage"},"thumbnailUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2017\/05\/ransomware-ciberseguretat-3.webp","datePublished":"2017-05-17T13:52:17+00:00","dateModified":"2017-05-17T15:32:44+00:00","author":{"@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/540d47fd9da63c4587cbae01b88e4db3"},"description":"An\u00e1lisis de por qu\u00e9 los ransomware, los ataques inform\u00e1ticos basados en la extorsi\u00f3n econ\u00f3mica, son una de las principales amenazas para empresas y usuarios","breadcrumb":{"@id":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/#primaryimage","url":"https:\/\/eurecat.org\/wp-content\/uploads\/2017\/05\/ransomware-ciberseguretat-3.webp","contentUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2017\/05\/ransomware-ciberseguretat-3.webp","width":1200,"height":659},{"@type":"BreadcrumbList","@id":"https:\/\/eurecat.org\/es\/ransomware-moviles-objetos-iot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/eurecat.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abEl ransomware ya se utiliza en m\u00f3viles y en 2 a\u00f1os se atacar\u00e1n objetos IoT\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/eurecat.org\/es\/#website","url":"https:\/\/eurecat.org\/es\/","name":"Eurecat","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurecat.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/540d47fd9da63c4587cbae01b88e4db3","name":"EurecatEM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurecat.org\/wp-content\/litespeed\/avatar\/ccde36d44b1cd8c84b09d53c1e5a94a8.jpg?ver=1784026185","url":"https:\/\/eurecat.org\/wp-content\/litespeed\/avatar\/ccde36d44b1cd8c84b09d53c1e5a94a8.jpg?ver=1784026185","contentUrl":"https:\/\/eurecat.org\/wp-content\/litespeed\/avatar\/ccde36d44b1cd8c84b09d53c1e5a94a8.jpg?ver=1784026185","caption":"EurecatEM"}}]}},"_links":{"self":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/25519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/comments?post=25519"}],"version-history":[{"count":0,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/25519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/media\/25539"}],"wp:attachment":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/media?parent=25519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/categories?post=25519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/tags?post=25519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}