{"id":50888,"date":"2018-02-26T17:13:24","date_gmt":"2018-02-26T17:13:24","guid":{"rendered":"https:\/\/eurecat.org\/cookit-mwc\/"},"modified":"2018-03-01T17:27:23","modified_gmt":"2018-03-01T17:27:23","slug":"cookit-mwc","status":"publish","type":"post","link":"https:\/\/eurecat.org\/es\/cookit-mwc\/","title":{"rendered":"Presentan una esp\u00e1tula inteligente para medir la salinidad de los alimentos con el m\u00f3vil"},"content":{"rendered":"<h2 style=\"text-align: center;\"><strong><span style=\"color: #000000;\">MOBILE WORLD CONGRESS 2018<\/span><\/strong><\/h2>\n<h1 style=\"text-align: center;\"><strong><span style=\"color: #000000;\">Presentan una esp\u00e1tula inteligente para medir la salinidad de los alimentos con el m\u00f3vil<\/span><\/strong><\/h1>\n<ul>\n<li style=\"text-align: center;\">\n<h2><strong><span style=\"color: #000000;\">El prototipo, codise\u00f1ado por Eurecat, permite medir el nivel de sodio autom\u00e1ticamente y llevar el historial en el m\u00f3vil.<\/span><\/strong><\/h2>\n<\/li>\n<li style=\"text-align: center;\">\n<h2><strong><span style=\"color: #000000;\">El dispositivo COOKiT, que se ha presentado en el Mobile World Congress, se probar\u00e1 con usuarios reales en Badalona.<\/span><\/strong><\/h2>\n<\/li>\n<li style=\"text-align: center;\">\n<h2><strong><span style=\"color: #000000;\">La esp\u00e1tula forma parte del proyecto Do CHANGE, que ha destacado de entre 20 propuestas en los premios Innovation Radar Forum de la Comisi\u00f3n Europea.<\/span><\/strong><\/h2>\n<\/li>\n<\/ul>\n<p><strong>El centro tecnol\u00f3gico Eurecat (miembro de Tecnio) ha presentado en la feria Mobile World Congress un prototipo de esp\u00e1tula inteligente que mide la salinidad de los alimentos autom\u00e1ticamente y permite hacer un seguimiento de la ingesta de sodio en tiempo real y desde el m\u00f3vil.<\/strong><\/p>\n<p>El dispositivo, llamado <strong>COOKiT<\/strong>, ha sido dise\u00f1ado parcialmente en Catalu\u00f1a, en el marco del proyecto <strong>Do CHANGE<\/strong>, que ha recibido el premio del p\u00fablico en los galardones Innovation Radar Forum 2017, promovidos por la Comisi\u00f3n Europea y que reconocen la innovaci\u00f3n tecnol\u00f3gica en distintos \u00e1mbitos.<\/p>\n<p>Seg\u00fan explica Daniel Blanco, Project Manager del desarrollo, Eurecat se ha encargado de desarrollar la tecnolog\u00eda de este utensilio que hace un seguimiento de la concentraci\u00f3n de sodio y que est\u00e1 \u201cespecialmente indicado para personas con problemas card\u00edacos\u201d.<\/p>\n<p>Adem\u00e1s de COOKiT, tambi\u00e9n integran la soluci\u00f3n Do CHANGE el dispositivo <strong>Horus<\/strong>, que informa sobre las propiedades nutricionales de los ingredientes, <strong>FLUiT<\/strong>, para hacer un seguimiento de los h\u00e1bitos de ingesta de l\u00edquidos con el m\u00f3vil, y <strong>Vire<\/strong>, que ayuda a la rehabilitaci\u00f3n de los pacientes con enfermedades cardiovasculares recopilando par\u00e1metros de actividad para promover un estilo de vida saludable.<\/p>\n<p>El proyecto Do CHANGE, une cuatro herramientas de mSalud o Salud M\u00f3vil que permiten hacer un seguimiento de par\u00e1metros como la ingesta de l\u00edquidos, sal o comida para promover una dieta equilibrada y adaptada a las necesidades m\u00e9dicas de cada paciente. El p\u00fablico presente en los premios, que se celebraron el 9 de noviembre en Budapest, deb\u00eda escoger entre una de entre 20 propuestas de innovaci\u00f3n tecnol\u00f3gica preseleccionadas.<\/p>\n<p>Do CHANGE, coordinado por la empresa holandesa Smart Homes, est\u00e1 integrado por un consorcio de 10 socios de tres pa\u00edses europeos y Taiw\u00e1n, entre universidades, centros sanitarios y de investigaci\u00f3n y empresas privadas. Desde Catalu\u00f1a, adem\u00e1s de Eurecat, participa en el proyecto la entidad p\u00fablica de ayuda a la dependencia Badalona Serveis Assistencials.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MOBILE WORLD CONGRESS 2018 Presentan una esp\u00e1tula inteligente para medir la salinidad de los alimentos con el m\u00f3vil El prototipo, codise\u00f1ado por Eurecat, permite medir el nivel de sodio autom\u00e1ticamente y llevar el historial en el m\u00f3vil. El dispositivo COOKiT, que se ha presentado en el Mobile World Congress, se probar\u00e1 con usuarios reales en  [&#8230;]<\/p>\n","protected":false},"author":12,"featured_media":45974,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[727,399,134],"tags":[728],"class_list":["post-50888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ferias","category-impresion-funcional","category-notas-de-prensa","tag-impressio-funcional-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentan una esp\u00e1tula para medir la sal de los alimentos con el m\u00f3vil<\/title>\n<meta name=\"description\" content=\"El prototipo, codise\u00f1ado por Eurecat, permite medir el nivel de sodio autom\u00e1ticamente y llevar el historial en el m\u00f3vil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurecat.org\/es\/cookit-mwc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentan una esp\u00e1tula para medir la sal de los alimentos con el m\u00f3vil\" \/>\n<meta property=\"og:description\" content=\"El prototipo, codise\u00f1ado por Eurecat, permite medir el nivel de sodio autom\u00e1ticamente y llevar el historial en el m\u00f3vil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurecat.org\/es\/cookit-mwc\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurecat\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-26T17:13:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-01T17:27:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurecat.org\/wp-content\/uploads\/2018\/01\/Do_Change.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"EurecatEG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"EurecatEG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/\"},\"author\":{\"name\":\"EurecatEG\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/def9217eded50ee57a9dc4cf0c883f80\"},\"headline\":\"Presentan una esp\u00e1tula inteligente para medir la salinidad de los alimentos con el m\u00f3vil\",\"datePublished\":\"2018-02-26T17:13:24+00:00\",\"dateModified\":\"2018-03-01T17:27:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/\"},\"wordCount\":443,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Do_Change.jpg\",\"keywords\":[\"impressi\u00f3 funcional\"],\"articleSection\":[\"Ferias\",\"Impresi\u00f3n funcional\",\"Notas de prensa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/\",\"url\":\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/\",\"name\":\"Presentan una esp\u00e1tula para medir la sal de los alimentos con el m\u00f3vil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Do_Change.jpg\",\"datePublished\":\"2018-02-26T17:13:24+00:00\",\"dateModified\":\"2018-03-01T17:27:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/def9217eded50ee57a9dc4cf0c883f80\"},\"description\":\"El prototipo, codise\u00f1ado por Eurecat, permite medir el nivel de sodio autom\u00e1ticamente y llevar el historial en el m\u00f3vil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Do_Change.jpg\",\"contentUrl\":\"https:\\\/\\\/eurecat.org\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Do_Change.jpg\",\"width\":\"1024\",\"height\":\"683\",\"caption\":\"smart cooking spoon CookIT, part of the DoCHANGE ecosystem with several designs for behavior modification with heartpatients. Design by Sander van Berlo, Industrial Design, TU Eindhoven\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/cookit-mwc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/eurecat.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentan una esp\u00e1tula inteligente para medir la salinidad de los alimentos con el m\u00f3vil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eurecat.org\\\/es\\\/\",\"name\":\"Eurecat\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurecat.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eurecat.org\\\/es\\\/#\\\/schema\\\/person\\\/def9217eded50ee57a9dc4cf0c883f80\",\"name\":\"EurecatEG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f40dd9b6ecd3e5c591f3c9b033e495ee0ec9877ba77249fbf268b3889350c824?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f40dd9b6ecd3e5c591f3c9b033e495ee0ec9877ba77249fbf268b3889350c824?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f40dd9b6ecd3e5c591f3c9b033e495ee0ec9877ba77249fbf268b3889350c824?s=96&d=mm&r=g\",\"caption\":\"EurecatEG\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentan una esp\u00e1tula para medir la sal de los alimentos con el m\u00f3vil","description":"El prototipo, codise\u00f1ado por Eurecat, permite medir el nivel de sodio autom\u00e1ticamente y llevar el historial en el m\u00f3vil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurecat.org\/es\/cookit-mwc\/","og_locale":"es_ES","og_type":"article","og_title":"Presentan una esp\u00e1tula para medir la sal de los alimentos con el m\u00f3vil","og_description":"El prototipo, codise\u00f1ado por Eurecat, permite medir el nivel de sodio autom\u00e1ticamente y llevar el historial en el m\u00f3vil.","og_url":"https:\/\/eurecat.org\/es\/cookit-mwc\/","og_site_name":"Eurecat","article_published_time":"2018-02-26T17:13:24+00:00","article_modified_time":"2018-03-01T17:27:23+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/eurecat.org\/wp-content\/uploads\/2018\/01\/Do_Change.jpg","type":"image\/jpeg"}],"author":"EurecatEG","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"EurecatEG","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eurecat.org\/es\/cookit-mwc\/#article","isPartOf":{"@id":"https:\/\/eurecat.org\/es\/cookit-mwc\/"},"author":{"name":"EurecatEG","@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/def9217eded50ee57a9dc4cf0c883f80"},"headline":"Presentan una esp\u00e1tula inteligente para medir la salinidad de los alimentos con el m\u00f3vil","datePublished":"2018-02-26T17:13:24+00:00","dateModified":"2018-03-01T17:27:23+00:00","mainEntityOfPage":{"@id":"https:\/\/eurecat.org\/es\/cookit-mwc\/"},"wordCount":443,"commentCount":0,"image":{"@id":"https:\/\/eurecat.org\/es\/cookit-mwc\/#primaryimage"},"thumbnailUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2018\/01\/Do_Change.jpg","keywords":["impressi\u00f3 funcional"],"articleSection":["Ferias","Impresi\u00f3n funcional","Notas de prensa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eurecat.org\/es\/cookit-mwc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eurecat.org\/es\/cookit-mwc\/","url":"https:\/\/eurecat.org\/es\/cookit-mwc\/","name":"Presentan una esp\u00e1tula para medir la sal de los alimentos con el m\u00f3vil","isPartOf":{"@id":"https:\/\/eurecat.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurecat.org\/es\/cookit-mwc\/#primaryimage"},"image":{"@id":"https:\/\/eurecat.org\/es\/cookit-mwc\/#primaryimage"},"thumbnailUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2018\/01\/Do_Change.jpg","datePublished":"2018-02-26T17:13:24+00:00","dateModified":"2018-03-01T17:27:23+00:00","author":{"@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/def9217eded50ee57a9dc4cf0c883f80"},"description":"El prototipo, codise\u00f1ado por Eurecat, permite medir el nivel de sodio autom\u00e1ticamente y llevar el historial en el m\u00f3vil.","breadcrumb":{"@id":"https:\/\/eurecat.org\/es\/cookit-mwc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurecat.org\/es\/cookit-mwc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eurecat.org\/es\/cookit-mwc\/#primaryimage","url":"https:\/\/eurecat.org\/wp-content\/uploads\/2018\/01\/Do_Change.jpg","contentUrl":"https:\/\/eurecat.org\/wp-content\/uploads\/2018\/01\/Do_Change.jpg","width":"1024","height":"683","caption":"smart cooking spoon CookIT, part of the DoCHANGE ecosystem with several designs for behavior modification with heartpatients. Design by Sander van Berlo, Industrial Design, TU Eindhoven"},{"@type":"BreadcrumbList","@id":"https:\/\/eurecat.org\/es\/cookit-mwc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/eurecat.org\/es\/"},{"@type":"ListItem","position":2,"name":"Presentan una esp\u00e1tula inteligente para medir la salinidad de los alimentos con el m\u00f3vil"}]},{"@type":"WebSite","@id":"https:\/\/eurecat.org\/es\/#website","url":"https:\/\/eurecat.org\/es\/","name":"Eurecat","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurecat.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/eurecat.org\/es\/#\/schema\/person\/def9217eded50ee57a9dc4cf0c883f80","name":"EurecatEG","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f40dd9b6ecd3e5c591f3c9b033e495ee0ec9877ba77249fbf268b3889350c824?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f40dd9b6ecd3e5c591f3c9b033e495ee0ec9877ba77249fbf268b3889350c824?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f40dd9b6ecd3e5c591f3c9b033e495ee0ec9877ba77249fbf268b3889350c824?s=96&d=mm&r=g","caption":"EurecatEG"}}]}},"_links":{"self":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/50888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/comments?post=50888"}],"version-history":[{"count":0,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/posts\/50888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/media\/45974"}],"wp:attachment":[{"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/media?parent=50888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/categories?post=50888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eurecat.org\/es\/wp-json\/wp\/v2\/tags?post=50888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}